{"id":2557,"date":"2022-05-17T11:34:47","date_gmt":"2022-05-17T11:34:47","guid":{"rendered":"https:\/\/urologiabielsalorente.com\/medical-team\/dra-ana-puigvert-martinez\/"},"modified":"2023-05-19T20:47:02","modified_gmt":"2023-05-19T20:47:02","slug":"dra-ana-puigvert-martinez","status":"publish","type":"page","link":"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/","title":{"rendered":"Dra. Ana Mar\u00eda Puigvert Mart\u00ednez"},"content":{"rendered":"<p>Dr. Ana Puigvert is a specialist in Andrology. She held the position of president of the Spanish Association of Andrology and Reproductive Sexual Medicine (ASESA) for 4 years.<br \/>\nCurrently, she is the president of the Foundation for Andrology, Sexual and Reproductive Medicine and is president of ANDRO (Ibero-American Association of Andrological Societies). She is also a member of the International Academy of Sexual Medicine.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dr. Ana Puigvert is a specialist in Andrology. She held the position of president of the Spanish Association of Andrology and Reproductive Sexual Medicine (ASESA) for 4 years. Currently, she is the president of the Foundation for Andrology, Sexual and Reproductive Medicine and is president of ANDRO (Ibero-American Association of Andrological Societies). She is also [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1877,"parent":2545,"menu_order":14,"comment_status":"closed","ping_status":"closed","template":"p-doctor.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2557","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dra. Ana Mar\u00eda Puigvert Mart\u00ednez - Urolog\u00eda Bielsa &amp; Lorente<\/title>\n<meta name=\"description\" content=\"Dr. Ana Puigvert is a specialist in Andrology. She is the president of the Foundation for Andrology, Sexual and Reproductive Medicine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dra. Ana Mar\u00eda Puigvert Mart\u00ednez - Urolog\u00eda Bielsa &amp; Lorente\" \/>\n<meta property=\"og:description\" content=\"Dr. Ana Puigvert is a specialist in Andrology. She is the president of the Foundation for Andrology, Sexual and Reproductive Medicine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/\" \/>\n<meta property=\"og:site_name\" content=\"Urolog\u00eda Bielsa &amp; Lorente\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-19T20:47:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/urologiabielsalorente.com\/webielsa23\/wp-content\/uploads\/2022\/12\/dra-Ana-Puigvert-cv.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"326\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/medical-team\\\/dra-ana-puigvert-martinez\\\/\",\"url\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/medical-team\\\/dra-ana-puigvert-martinez\\\/\",\"name\":\"Dra. Ana Mar\u00eda Puigvert Mart\u00ednez - Urolog\u00eda Bielsa &amp; Lorente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/medical-team\\\/dra-ana-puigvert-martinez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/medical-team\\\/dra-ana-puigvert-martinez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/urologiabielsalorente.com\\\/webielsa23\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/dra-Ana-Puigvert-cv.jpg\",\"datePublished\":\"2022-05-17T11:34:47+00:00\",\"dateModified\":\"2023-05-19T20:47:02+00:00\",\"description\":\"Dr. Ana Puigvert is a specialist in Andrology. She is the president of the Foundation for Andrology, Sexual and Reproductive Medicine.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/medical-team\\\/dra-ana-puigvert-martinez\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/medical-team\\\/dra-ana-puigvert-martinez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/medical-team\\\/dra-ana-puigvert-martinez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/urologiabielsalorente.com\\\/webielsa23\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/dra-Ana-Puigvert-cv.jpg\",\"contentUrl\":\"https:\\\/\\\/urologiabielsalorente.com\\\/webielsa23\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/dra-Ana-Puigvert-cv.jpg\",\"width\":326,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/medical-team\\\/dra-ana-puigvert-martinez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our Team\",\"item\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/equipo-medico\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dra. Ana Mar\u00eda Puigvert Mart\u00ednez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/\",\"name\":\"Urolog\u00eda Bielsa &amp; Lorente\",\"description\":\"Equipo oficial de Urolog\u00eda del Hospital Quir\u00f3n Salud de Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/#organization\",\"name\":\"Urolog\u00eda Bielsa &amp; Lorente\",\"url\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/urologiabielsalorente.com\\\/webielsa23\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/solicionesPersonales1024-e1402499581900.jpg\",\"contentUrl\":\"https:\\\/\\\/urologiabielsalorente.com\\\/webielsa23\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/solicionesPersonales1024-e1402499581900.jpg\",\"width\":1024,\"height\":570,\"caption\":\"Urolog\u00eda Bielsa &amp; Lorente\"},\"image\":{\"@id\":\"https:\\\/\\\/urologiabielsalorente.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urologia-bielsa-lorente\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dra. Ana Mar\u00eda Puigvert Mart\u00ednez - Urolog\u00eda Bielsa &amp; Lorente","description":"Dr. Ana Puigvert is a specialist in Andrology. She is the president of the Foundation for Andrology, Sexual and Reproductive Medicine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/","og_locale":"en_US","og_type":"article","og_title":"Dra. Ana Mar\u00eda Puigvert Mart\u00ednez - Urolog\u00eda Bielsa &amp; Lorente","og_description":"Dr. Ana Puigvert is a specialist in Andrology. She is the president of the Foundation for Andrology, Sexual and Reproductive Medicine.","og_url":"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/","og_site_name":"Urolog\u00eda Bielsa &amp; Lorente","article_modified_time":"2023-05-19T20:47:02+00:00","og_image":[{"width":326,"height":340,"url":"https:\/\/urologiabielsalorente.com\/webielsa23\/wp-content\/uploads\/2022\/12\/dra-Ana-Puigvert-cv.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/","url":"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/","name":"Dra. Ana Mar\u00eda Puigvert Mart\u00ednez - Urolog\u00eda Bielsa &amp; Lorente","isPartOf":{"@id":"https:\/\/urologiabielsalorente.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/#primaryimage"},"image":{"@id":"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/#primaryimage"},"thumbnailUrl":"https:\/\/urologiabielsalorente.com\/webielsa23\/wp-content\/uploads\/2022\/12\/dra-Ana-Puigvert-cv.jpg","datePublished":"2022-05-17T11:34:47+00:00","dateModified":"2023-05-19T20:47:02+00:00","description":"Dr. Ana Puigvert is a specialist in Andrology. She is the president of the Foundation for Andrology, Sexual and Reproductive Medicine.","breadcrumb":{"@id":"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/#primaryimage","url":"https:\/\/urologiabielsalorente.com\/webielsa23\/wp-content\/uploads\/2022\/12\/dra-Ana-Puigvert-cv.jpg","contentUrl":"https:\/\/urologiabielsalorente.com\/webielsa23\/wp-content\/uploads\/2022\/12\/dra-Ana-Puigvert-cv.jpg","width":326,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/urologiabielsalorente.com\/en\/medical-team\/dra-ana-puigvert-martinez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/urologiabielsalorente.com\/en\/"},{"@type":"ListItem","position":2,"name":"Our Team","item":"https:\/\/urologiabielsalorente.com\/en\/equipo-medico\/"},{"@type":"ListItem","position":3,"name":"Dra. Ana Mar\u00eda Puigvert Mart\u00ednez"}]},{"@type":"WebSite","@id":"https:\/\/urologiabielsalorente.com\/en\/#website","url":"https:\/\/urologiabielsalorente.com\/en\/","name":"Urolog\u00eda Bielsa &amp; Lorente","description":"Equipo oficial de Urolog\u00eda del Hospital Quir\u00f3n Salud de Barcelona","publisher":{"@id":"https:\/\/urologiabielsalorente.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/urologiabielsalorente.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/urologiabielsalorente.com\/en\/#organization","name":"Urolog\u00eda Bielsa &amp; Lorente","url":"https:\/\/urologiabielsalorente.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/urologiabielsalorente.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/urologiabielsalorente.com\/webielsa23\/wp-content\/uploads\/2014\/04\/solicionesPersonales1024-e1402499581900.jpg","contentUrl":"https:\/\/urologiabielsalorente.com\/webielsa23\/wp-content\/uploads\/2014\/04\/solicionesPersonales1024-e1402499581900.jpg","width":1024,"height":570,"caption":"Urolog\u00eda Bielsa &amp; Lorente"},"image":{"@id":"https:\/\/urologiabielsalorente.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/urologia-bielsa-lorente\/"]}]}},"_links":{"self":[{"href":"https:\/\/urologiabielsalorente.com\/en\/wp-json\/wp\/v2\/pages\/2557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urologiabielsalorente.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/urologiabielsalorente.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/urologiabielsalorente.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urologiabielsalorente.com\/en\/wp-json\/wp\/v2\/comments?post=2557"}],"version-history":[{"count":4,"href":"https:\/\/urologiabielsalorente.com\/en\/wp-json\/wp\/v2\/pages\/2557\/revisions"}],"predecessor-version":[{"id":2951,"href":"https:\/\/urologiabielsalorente.com\/en\/wp-json\/wp\/v2\/pages\/2557\/revisions\/2951"}],"up":[{"embeddable":true,"href":"https:\/\/urologiabielsalorente.com\/en\/wp-json\/wp\/v2\/pages\/2545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urologiabielsalorente.com\/en\/wp-json\/wp\/v2\/media\/1877"}],"wp:attachment":[{"href":"https:\/\/urologiabielsalorente.com\/en\/wp-json\/wp\/v2\/media?parent=2557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}